{"id":44140,"date":"2022-08-02T10:00:41","date_gmt":"2022-08-02T08:00:41","guid":{"rendered":"https:\/\/www.comparasemplice.it\/informazioni\/?p=44140"},"modified":"2022-07-07T14:35:18","modified_gmt":"2022-07-07T12:35:18","slug":"kena-hotspot-non-funziona-come-risolvere","status":"publish","type":"post","link":"https:\/\/www.comparasemplice.it\/informazioni\/tim\/kena-hotspot-non-funziona-come-risolvere","title":{"rendered":"Kena hotspot non funziona: come risolvere"},"content":{"rendered":"<p><strong>Kena Mobi<\/strong>le \u00e8 il primo semivirtuale ad essere arrivato sul mercato italiano: controllato direttamente da <strong>TIM<\/strong>, il gestore low cost ha anticipato l\u2019arrivo di Iliad in Italia e si \u00e8 ritagliato una fetta consistente di utenza, grazie ad un ottimo mix di convenienza, copertura e trasparenza sulle condizioni tariffarie.<\/p>\n<p>Attualmente<strong> Kena Mobile conta poco meno di 2 milioni di utenti<\/strong>. Il listino tariffe parte da circa 8\u20ac al mese, con soluzioni tutto compreso e connessione dati ad una<strong> velocit\u00e0 massima di 30 o 60 Mbps in 4G<\/strong>, a seconda dell\u2019offerta scelta. La rete in cui opera \u00e8, ovviamente, TIM, una delle pi\u00f9 capillari a livello nazionale.<\/p>\n<p>Tutte le offerte Kena Mobile prevedono, tra le altre cose, l\u2019<strong>hotspot gratuito<\/strong> e generalmente non \u00e8 necessario effettuare alcuna configurazione manuale: <strong>il settaggio corretto viene scaricato e installato automaticamente<\/strong> dopo aver inserito la sim nel telefono. Lo stesso operatore specifica che \u201c<em>il tuo telefono si configurer\u00e0 automaticamente non appena la SIM Kena Mobile sar\u00e0 attivata in rete: baster\u00e0 solo accettare il messaggio auto-configurante\u00a0che riceverai alla prima accensione<\/em>\u201d<\/p>\n<p>In alcuni casi, per\u00f2, \u00e8 possibile che ci\u00f2 non avvenga e che si sia impossibilitati a navigare o a condividere i giga del piano con altri dispositivi: che cosa fare in questi casi?<\/p>\n<p>Il problema \u00e8 spesso legato alla mancata ricezione della configurazione automatica iniziale, al momento del primo inserimento della scheda sullo smartphone. Inoltre i <strong>parametri APN<\/strong> (Access Point Name), necessari per il corretto funzionamento della rete dati, potrebbero non essere corretti o essere parziali.<\/p>\n<p>Vediamo, quindi, che cosa fare quando il Kena hotspot non funziona, partendo con i dati APN corretti del gestore.<\/p>\n<p>Sommario<\/p><div class=\"sommario\" id=\"indice\"><ol><li><a class=\"link_sommario\" href=\"#apn-kena-mobile-i-parametri-corretti\">APN Kena Mobile: i parametri corretti<\/a><\/li><li><a class=\"link_sommario\" href=\"#kena-hotspot-iphone-non-funziona-cosa-fare\">Kena hotspot iPhone non funziona: cosa fare<\/a><\/li><li><a class=\"link_sommario\" href=\"#kena-hotspot-android-non-funziona-come-risolvere\">Kena hotspot Android non funziona: come risolvere<\/a><\/li><\/ol><\/div>\n<h2>APN Kena Mobile: i parametri corretti<\/h2>\n<p>Di base, i parametri APN necessari affinch\u00e9 la connessione Internet mobile Kena funzioni sono i seguenti:<\/p>\n<ul>\n<li>Nome: <strong>Kenamobile<\/strong> (o qualsiasi altro nome si desideri)<\/li>\n<li>APN: <strong>web.kenamobile.it<\/strong><\/li>\n<li>Tipo APN: <strong>default<\/strong><\/li>\n<\/ul>\n<p>Il resto delle voci del profilo APN pu\u00f2 rimanere quello di default. Tuttavia<strong>, se l\u2019hotspot Kena continua a non funzionare<\/strong>, sulla riga \u201cTipo APN\u201d \u00e8 consigliabile inserire la seguente stringa:<\/p>\n<p><strong>default,supl,dun<\/strong><\/p>\n<p>Lo ripetiamo ancora una volta: nella stragrande maggioranza dei casi non \u00e8 necessario impostare manualmente l\u2019APN perch\u00e9 la configurazione avviene automaticamente non appena inserite la scheda Kena sul cellulare. Potrebbe comunque essere <strong>utile conoscere questi dati, ad esempio se notate dei malfunzionamenti sulla connessione del telefono o se volete utilizzare un router 4G con la sim Kena<\/strong>.<\/p>\n<h2>Kena hotspot iPhone non funziona: cosa fare<\/h2>\n<p>Se la connessione dat Knai su iPhone non funziona o non riuscite a condividerla con altri dispositivi attraverso l\u2019hotspot del telefono, seguite questi semplici passaggi:<\/p>\n<ul>\n<li>Andare su <strong>Impostazioni\/Cellulare\/Rete Dati cellulare<\/strong>;<\/li>\n<li>Sulla riga \u201c<strong>Hotspot Personale<\/strong>\u201d, inserire l\u2019indirizzo APN \u201cweb.kenamobile.it&#8221;;<\/li>\n<li>Attivare l\u2019interruttore \u201c<strong>Consenti agli altri di accedere<\/strong>\u201d.<\/li>\n<\/ul>\n<p>Fate swipe verso destra per tornare indietro: in questo modo le nuove impostazioni verranno salvate.<\/p>\n<h2>Kena hotspot Android non funziona: come risolvere<\/h2>\n<p>Se possedete uno smartphone Android e la connessione o l\u2019hotspot Kena non funzionano,<strong> il percorso per accedere alla modifica dell\u2019APN varia a seconda del dispositivo che state utilizzando<\/strong>: i produttori, infatti, modificano spesso l\u2019interfaccia, in alcuni casi anche profondamente.<\/p>\n<p>Possiamo comunque dare delle linee guida prendendo come esempio le impostazioni di uno smartphone Android \u201cstock\u201d, non personalizzato con interfacce proprietarie:<\/p>\n<ul>\n<li>Andare su <strong>Impostazioni\/Rete e Internet\/Rete Mobile\/Avanzati\/Punti d\u2019accesso<\/strong>;<\/li>\n<li>Toccare sull\u2019APN Kena gi\u00e0 presente o crearne uno nuovo (toccando sui <strong>tre puntini in alto a destra<\/strong> della schermata e scegliendo l\u2019opzione \u201c<strong>Nuovo APN<\/strong>\u201d);<\/li>\n<li>Inserire l\u2019APN \u201c<strong>web.kenamobile.it<\/strong>&#8221; e gli altri parametri visti in precedenza;<\/li>\n<li>Toccare infine sui tre puntini in alto a destra e scegliere l\u2019opzione \u201c<strong>Salva<\/strong>\u201d.<\/li>\n<\/ul>\n<p><strong>Tornando indietro sulla pagina precedente, selezionate l\u2019APN appena creato<\/strong> (qualora non lo fosse gi\u00e0 in automatico) e riavviate la connessione: ora la rete dati e l\u2019hotspot Kena dovrebbero funzionare.<\/p>\n<p>Abbiamo visto le soluzioni pi\u00f9 comuni quando il Kena hotspot non funziona o notate dei malfunzionamenti sulla connessione Internet del cellulare dopo essere passati all\u2019operatore di TIM. Non solo: i parametri APN Kena vi possono essere utili per configurare manualmente dispositivi differenti su cui inserire la sim della compagnia, ad esempio un modem 4G o una <a href=\"https:\/\/www.comparasemplice.it\/informazioni\/cellulari\/saponetta-internet-offerte-degli-operatori\"><strong>saponetta Internet<\/strong><\/a>.<\/p>\n<p>Se, per\u00f2, i malfunzionamenti dovessero persistere anche dopo aver seguito correttamente la guida, il nostro consiglio \u00e8 di <a href=\"https:\/\/www.comparasemplice.it\/informazioni\/telefonia\/servizio-clienti-kena-mobile-come-parlare-con-un-operatore\"><strong>contattare l\u2019assistenza Kena Mobile<\/strong><\/a>: il numero di telefono \u00e8 il <strong>181<\/strong>, gratuito dai numeri del gestore e da rete fissa TIM. Il customer care risponde <strong>7 giorni su 7, dalle ore 8 alle 22<\/strong>. In alternativa potete utilizzare i canali social ufficiali di Kena oppure la chat che trovate sul sito ufficiale dell\u2019operatore, <strong>www.kenamobile.it<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kena Mobile \u00e8 il primo semivirtuale ad essere arrivato sul mercato italiano: controllato direttamente da TIM, il gestore low cost&#8230;<\/p>\n","protected":false},"author":49,"featured_media":44141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28,44],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kena hotspot non funziona: come risolvere | ComparaSemplice.it<\/title>\n<meta name=\"description\" content=\"Avete dei problemi con l&#039;hotspot o la connessione Internet Kena? La condivisione non funziona? Ecco una guida dettagliata per risolvere e i parametri APN.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparasemplice.it\/informazioni\/tim\/kena-hotspot-non-funziona-come-risolvere\" \/>\n<meta name=\"author\" content=\"Silvio Spina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparasemplice.it\/informazioni\/tim\/kena-hotspot-non-funziona-come-risolvere#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.comparasemplice.it\/informazioni\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kena hotspot non funziona: come risolvere\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kena hotspot non funziona: come risolvere | ComparaSemplice.it","description":"Avete dei problemi con l'hotspot o la connessione Internet Kena? La condivisione non funziona? Ecco una guida dettagliata per risolvere e i parametri APN.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparasemplice.it\/informazioni\/tim\/kena-hotspot-non-funziona-come-risolvere","author":"Silvio Spina","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comparasemplice.it\/informazioni\/tim\/kena-hotspot-non-funziona-come-risolvere#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.comparasemplice.it\/informazioni"},{"@type":"ListItem","position":2,"name":"Kena hotspot non funziona: come risolvere"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/44140"}],"collection":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/comments?post=44140"}],"version-history":[{"count":3,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/44140\/revisions"}],"predecessor-version":[{"id":49483,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/44140\/revisions\/49483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/media\/44141"}],"wp:attachment":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/media?parent=44140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/categories?post=44140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/tags?post=44140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}