{"id":44203,"date":"2022-05-31T12:38:46","date_gmt":"2022-05-31T10:38:46","guid":{"rendered":"https:\/\/www.comparasemplice.it\/informazioni\/?p=44203"},"modified":"2024-10-29T17:53:38","modified_gmt":"2024-10-29T16:53:38","slug":"come-registrare-un-video-con-la-webcam-del-mac-3-metodi-gratuiti","status":"publish","type":"post","link":"https:\/\/www.comparasemplice.it\/informazioni\/news\/come-registrare-un-video-con-la-webcam-del-mac-3-metodi-gratuiti","title":{"rendered":"Come registrare un video con la Webcam del Mac: 3 metodi gratuiti"},"content":{"rendered":"<p>I computer di casa Apple, come i Macbook, gli iMac e i Mac Mini, sono particolarmente apprezzati e utilizzati da creators, artisti e studenti, grazie soprattutto alla presenza di applicativi e strumenti pensati ad hoc per queste particolari fasce di utenza. In realt\u00e0 con il passare del tempo l\u2019ecosistema Apple si \u00e8 esteso anche alla clientela Consumer pi\u00f9 generalista, seppure con una quota di mercato inferiore rispetto alla controparte PC, grazie anche alla cura nei dettagli, all&#8217;estetica e alla creazione di un ecosistema di ottimo livello, che permette ai vari dispositivi della Mela (Mac, iPad, iPhone, etc&#8230;) di interagire in modo semplice e di avere delle funzionalit\u00e0 avanzate di comunicazione tra device (pensiamo, ad esempio, ad AirPlay, Handoff e Continuity).<\/p>\n<p>I costi mediamente pi\u00f9 alti rispetto alla concorrenza non sono una novit\u00e0; \u00e8 anche vero, per\u00f2, che Apple offre fin da subito <strong>un ampio ventaglio di programmi e utility gratuiti, estremamente gradevoli nell\u2019interfaccia e molto semplici da utilizzare<\/strong>.<\/p>\n<p>Se avete cominciato a leggere questa guida, probabilmente<strong> avete gi\u00e0 acquistato un computer di casa Apple e volete imparare a registrare dei video direttamente dalla Webcam<\/strong> (che la casa produttrice chiama solitamente \u201cfotocamera FaceTime\u201d): le motivazioni possono essere diverse, ad esempio volete realizzare delle videolezioni, una performance musicale o un contenuto da condividere sui social.<\/p>\n<p>Come vedremo tra poco, <strong>non \u00e8 necessario essere degli esperti per registrare un video con un Mac<\/strong> e, inoltre, non avrete nemmeno bisogno di scaricare dei programmi aggiuntivi: la maggior parte delle applicazioni che vi servono sono gi\u00e0 installate sul computer fin dal momento dell\u2019acquisto.<\/p>\n<p>Insomma, c<strong>ome registrare un video con la Webcam del Mac<\/strong>? Ecco 3 metodi gratuiti:<\/p>\n<ul>\n<li>usando l\u2019app Photo Booth;<\/li>\n<li>usando l\u2019app Quick Time;<\/li>\n<li>usando l\u2019app iMovie.<\/li>\n<\/ul>\n<p>Nei prossimi paragrafi vedremo la procedura da seguire, passo per passo, in base al programma che sceglierete di utilizzare.<\/p>\n<p>Sommario<\/p><div class=\"sommario\" id=\"indice\"><ol><li><a class=\"link_sommario\" href=\"#registrare-un-video-dalla-webcam-mac-con-photo-booth\">Registrare un video dalla Webcam Mac con Photo Booth<\/a><\/li><li><a class=\"link_sommario\" href=\"#registrare-video-da-mac-con-quicktime\">Registrare video da Mac con QuickTime<\/a><\/li><li><a class=\"link_sommario\" href=\"#come-registrare-video-dalla-webcam-del-mac-da-imovie\">Come registrare video dalla Webcam del Mac da iMovie<\/a><\/li><\/ol><\/div>\n<h2>Registrare un video dalla Webcam Mac con Photo Booth<\/h2>\n<p>Uno dei metodi pi\u00f9 semplici per registrare un video con la Webcam Mac senza dover scaricare alcun software \u00e8 utilizzando <strong>PhotoBooth<\/strong>, un programma preinstallato sul sistema che si pu\u00f2 trovare sulla cartella Applicazioni (oppure cercando tramite Launchpad o Spotlight). La sua sua funzione primaria \u00e8 scattare foto, applicando in tempo reale effetti grafici e divertenti per personalizzare le immagini catturate.<\/p>\n<p>Registrare un video con PhotoBooth \u00e8 molto semplice:<\/p>\n<ul>\n<li>dopo aver aperto l\u2019applicazione,<strong> cliccare sull\u2019icona della videocamera<\/strong> in basso a sinistra;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44204 size-medium\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/modalita-video-photo-booth-300x233.jpg\" alt=\"\" width=\"300\" height=\"233\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/modalita-video-photo-booth-300x233.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/modalita-video-photo-booth.jpg 740w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ul>\n<li>cliccare sul <strong>pulsante rosso di registrazione<\/strong> e attendere la fine del conto alla rovescia;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-44205\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/conto-alla-rovescia-photo-booth-300x234.jpg\" alt=\"\" width=\"300\" height=\"234\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/conto-alla-rovescia-photo-booth-300x234.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/conto-alla-rovescia-photo-booth.jpg 725w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ul>\n<li>la registrazione video \u00e8 cominciata e pu\u00f2 essere interrotta in qualsiasi momento <strong>cliccando il pulsante di Stop<\/strong>.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-44206\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/pulsante-stop-photo-booth-300x238.jpg\" alt=\"\" width=\"300\" height=\"238\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/pulsante-stop-photo-booth-300x238.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/pulsante-stop-photo-booth.jpg 716w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ul>\n<li>Una volta terminata la registrazione, <strong>il video viene salvato automaticamente all\u2019interno di Photo Booth<\/strong> e pu\u00f2 essere richiamato in qualsiasi momento cliccando sopra la miniatura in basso. Per eliminarla, baster\u00e0 fare<strong> click sulla \u201cx\u201d in alto a destra della miniatura del video<\/strong>.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-44207\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/video-salvato-photobooth-300x238.jpg\" alt=\"\" width=\"300\" height=\"238\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/video-salvato-photobooth-300x238.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/video-salvato-photobooth.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Ricordiamo, infine, che \u00e8 possibile spostare i video da Photo Booth verso un&#8217;altra posizione nel Mac, semplicemente<strong> trascinando la miniatura verso la destinazione desiderata (drag &amp; drop)<\/strong>.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-44208\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/trascinamento-video-photobooth-300x115.jpg\" alt=\"\" width=\"300\" height=\"115\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/trascinamento-video-photobooth-300x115.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/trascinamento-video-photobooth-768x294.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/trascinamento-video-photobooth.jpg 1088w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2>Registrare video da Mac con QuickTime<\/h2>\n<p>QuickTime Player \u00e8 un altro programma preinstallato sui Mac che consente, tra le varie funzionalit\u00e0 disponibili, di<strong> registrare dei video direttamente dalla Webcam del computer<\/strong>, ma anche da videocamere esterne collegate via USB. Come Photo Booth, <strong>lo si pu\u00f2 trovare sulla cartella Applicazioni di MacOS, su Launchpad o cercando il nome su Spotlight<\/strong>.<\/p>\n<p>Per far partire una registrazione video su QuickTime \u00e8 necessario seguire i seguenti passaggi:<\/p>\n<ul>\n<li>aprire QuickTime Player;<\/li>\n<li>dalla barra menu in alto, cliccare su &#8220;<strong>File<\/strong>&#8221; e su &#8220;<strong>Nuova registrazione filmato<\/strong>&#8220;;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44210 size-full\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-menu-file-registrazione-filmato.jpg\" alt=\"\" width=\"486\" height=\"403\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-menu-file-registrazione-filmato.jpg 486w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-menu-file-registrazione-filmato-300x249.jpg 300w\" sizes=\"(max-width: 486px) 100vw, 486px\" \/><\/p>\n<ul>\n<li>quando la finestra video \u00e8 aperta, <strong>cliccare sul pulsante rosso di registrazione<\/strong> per cominciare;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44211 \" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-pulsante-registrazione.jpg\" alt=\"\" width=\"488\" height=\"327\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-pulsante-registrazione.jpg 409w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-pulsante-registrazione-300x201.jpg 300w\" sizes=\"(max-width: 488px) 100vw, 488px\" \/><\/p>\n<ul>\n<li>se si vuole usare una Webcam diversa da quella del Mac (ad esempio connessa al computer tramite USB), <strong>prima della registrazione bisogna cliccare sulla freccetta accanto al pulsante rosso e scegliere la fonte desiderata<\/strong>. Da questo particolare menu, inoltre, \u00e8 possibile fare ulteriori modifiche, ad esempio <strong>scegliere una sorgente audio diversa e impostare una qualit\u00e0 di registrazione pi\u00f9 alta<\/strong>;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44212\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-menu-registrazione-fonti-300x217.jpg\" alt=\"\" width=\"500\" height=\"362\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-menu-registrazione-fonti-300x217.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-menu-registrazione-fonti.jpg 427w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<ul>\n<li>la registrazione pu\u00f2 essere interrotta in qualsiasi momento cliccando sul <strong>pulsante<\/strong> <strong>Stop<\/strong>.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44213\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-pulsante-stop-300x157.jpg\" alt=\"\" width=\"495\" height=\"259\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-pulsante-stop-300x157.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-pulsante-stop.jpg 500w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/p>\n<p>Dopo aver bloccato la registrazione, il video viene aperto automaticamente, pronto per essere guardato. <strong>\u00c8 possibile salvarlo sul computer con tre semplici metodi<\/strong>;<\/p>\n<p>1.<strong> cliccando sulla \u201cx\u201d della finestra del video<\/strong> per chiudere la finestra sul pulsante \u201cSalva\u201d;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44214\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-salvare-video-x-300x166.jpg\" alt=\"\" width=\"474\" height=\"262\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-salvare-video-x-300x166.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-salvare-video-x-768x425.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-salvare-video-x-1200x664.jpg 1200w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-salvare-video-x.jpg 1281w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>2. cliccando su &#8220;<strong>File<\/strong>&#8221; e &#8220;<strong>Salva<\/strong>&#8220;dalla barra del menu in alto di Quick Time;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44215\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-file-salva-300x245.jpg\" alt=\"\" width=\"429\" height=\"351\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-file-salva-300x245.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/quicktime-file-salva.jpg 477w\" sizes=\"(max-width: 429px) 100vw, 429px\" \/><\/p>\n<p style=\"text-align: left;\">3. ,<strong>premendo contemporaneamente i tasti Command e S della tastiera\u00a0<\/strong>e confermare poi con &#8220;<strong>Salva<\/strong>&#8220;.<\/p>\n<h2>Come registrare video dalla Webcam del Mac da iMovie<\/h2>\n<p>iMovie \u00e8 un interessante programma che Apple offre gratis ai propri utenti. Si tratta in realt\u00e0 di una vera e propria <strong>applicazione di video editing<\/strong>, una versione semplificata e pi\u00f9 \u201cuser friendly\u201d del software professionale Final Cut Pro, con la quale condivide alcune funzioni e parte della grafica.<\/p>\n<p>Al contrario di Photo Booth e Quick Time Player, i<strong>Movie solitamente non \u00e8 preinstallato nel Mac<\/strong>: tuttavia <strong>pu\u00f2 essere scaricato gratis dall\u2019App Store, digitando \u201ciMovie\u201d dalla barra di ricerca e poi cliccando su \u201cOttieni\u201d\u00a0<\/strong>(\u00e8 consigliabile farlo tramite una rete Internet casa o mobile di qualit\u00e0 per scaricarlo rapidamente, trattandosi di oltre 2 GB di dati)\u00a0Una volta scaricato, <strong>iMovie sar\u00e0 presente nella cartella Applicazioni<\/strong>, insieme a tutti gli altri programmi installati sul Mac.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44217\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-app-store-300x248.jpg\" alt=\"\" width=\"445\" height=\"368\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-app-store-300x248.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-app-store-768x636.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-app-store-1200x993.jpg 1200w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-app-store.jpg 1224w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><\/p>\n<p>Oltre al video editing, <strong>quest\u2019app pu\u00f2 essere utilizzata per registrare dei video da qualsiasi fonte, compresa la fotocamera FaceTime integrata nel computer<\/strong>.<\/p>\n<p>Ma come si pu\u00f2 registrare un video dalla Webcam del Mac usando iMovie? Ecco i passaggi da seguire:<\/p>\n<ul>\n<li>una volta scaricato e aperto iMovie, <strong>cliccare sull\u2019icona<\/strong> \u201c<strong>+<\/strong>\u201d per creare un nuovo filmato;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44216\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-crea-filmato-300x159.jpg\" alt=\"\" width=\"461\" height=\"244\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-crea-filmato-300x159.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-crea-filmato-768x408.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-crea-filmato-1200x637.jpg 1200w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-crea-filmato.jpg 1435w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/><\/p>\n<ul>\n<li>dalla schermata principale del programma, cliccare su \u201c<strong>Importa file multimediali<\/strong>\u201d;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44218\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-importa-file-multimediali-300x205.jpg\" alt=\"\" width=\"456\" height=\"311\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-importa-file-multimediali-300x205.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-importa-file-multimediali-768x525.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-importa-file-multimediali.jpg 973w\" sizes=\"(max-width: 456px) 100vw, 456px\" \/><\/p>\n<ul>\n<li>cliccate su \u201c<strong>OK<\/strong>\u201d nelle finestre pop-up \u201c<strong>iMovie vorrebbe accedere alla fotocamera<\/strong>\u201d e \u201c<strong>iMovie vorrebbe accedere al microfono<\/strong>\u201d;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44219\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-permessi-fotocamera-audio-300x145.jpg\" alt=\"\" width=\"451\" height=\"218\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-permessi-fotocamera-audio-300x145.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-permessi-fotocamera-audio-768x372.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-permessi-fotocamera-audio.jpg 957w\" sizes=\"(max-width: 451px) 100vw, 451px\" \/><\/p>\n<ul>\n<li>dalla finestra \u201c<strong>Importa<\/strong>\u201d, sul menu laterale, cliccare sulla voce \u201c<strong>Fotocamera HD FaceTime<\/strong>\u201d, presente sotto la sezione \u201c<strong>Videocamere<\/strong>\u201d;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44220\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-menu-importa-194x300.jpg\" alt=\"\" width=\"260\" height=\"402\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-menu-importa-194x300.jpg 194w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-menu-importa.jpg 248w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/p>\n<p>una volta aperta la finestra della Webcam, <strong>cliccare sul pulsante di registrazione<\/strong>;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44221\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-pulsante-registrazione-300x218.jpg\" alt=\"\" width=\"460\" height=\"334\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-pulsante-registrazione-300x218.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-pulsante-registrazione-768x557.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-pulsante-registrazione-1200x870.jpg 1200w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-pulsante-registrazione.jpg 1314w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/p>\n<ul>\n<li><strong>cliccare lo stesso pulsante per interrompere la registrazione<\/strong>;<\/li>\n<li><strong>trascinare i video registrati nella Timeline<\/strong> di iMovie;<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44222\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-timeline-300x168.jpg\" alt=\"\" width=\"461\" height=\"258\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-timeline-300x168.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-timeline-768x431.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-timeline-1200x673.jpg 1200w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-timeline.jpg 1342w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/><\/p>\n<p>una volta completate le modifiche, <strong>il video pu\u00f2 essere esportato cliccando sul pulsante di condivisione posto sull\u2019angolo in alto a destra della finestra e sull\u2019opzione \u201cEsporta File&#8221;<\/strong>;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44223\" src=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-esporta-file-300x148.jpg\" alt=\"\" width=\"463\" height=\"228\" srcset=\"https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-esporta-file-300x148.jpg 300w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-esporta-file-768x378.jpg 768w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-esporta-file-1500x738.jpg 1500w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-esporta-file-1200x590.jpg 1200w, https:\/\/www.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/11\/imovie-esporta-file.jpg 1564w\" sizes=\"(max-width: 463px) 100vw, 463px\" \/><\/p>\n<ul>\n<li>scegliete le opzioni desiderate per la qualit\u00e0 video e confermate l\u2019esportazione.<\/li>\n<\/ul>\n<p>Come si pu\u00f2 intuire, iMovie \u00e8 un\u2019app molto pi\u00f9 avanzata e complessa rispetto a Photo Booth e Quick Time: <strong>\u00e8 consigliabile usarla per registrare dalla Webcam solo se si vuole editare il video o se si vuole salvare un\u2019unica registrazione composta da pi\u00f9 video insieme<\/strong>.<\/p>\n<p>Ecco, quindi, come registrare un video con la Webcam del Mac in modo del tutto gratis e semplice, senza dover scaricare applicazioni a pagamento o esterne all&#8217;ecosistema Apple. Voi quale programma preferite? Fatecelo sapere lasciando un commento qui sotto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I computer di casa Apple, come i Macbook, gli iMac e i Mac Mini, sono particolarmente apprezzati e utilizzati da&#8230;<\/p>\n","protected":false},"author":49,"featured_media":44224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>3 modi gratis per registrare un video con la Webcam del Mac<\/title>\n<meta name=\"description\" content=\"Volete sapere come registrare un video con la Webcam del Mac? Ecco tre applicazioni gratis: Photo Booth, Quick Time e iMovie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparasemplice.it\/informazioni\/news\/come-registrare-un-video-con-la-webcam-del-mac-3-metodi-gratuiti\" \/>\n<meta name=\"author\" content=\"Silvio Spina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparasemplice.it\/informazioni\/news\/come-registrare-un-video-con-la-webcam-del-mac-3-metodi-gratuiti#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.comparasemplice.it\/informazioni\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come registrare un video con la Webcam del Mac: 3 metodi gratuiti\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 modi gratis per registrare un video con la Webcam del Mac","description":"Volete sapere come registrare un video con la Webcam del Mac? Ecco tre applicazioni gratis: Photo Booth, Quick Time e iMovie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparasemplice.it\/informazioni\/news\/come-registrare-un-video-con-la-webcam-del-mac-3-metodi-gratuiti","author":"Silvio Spina","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comparasemplice.it\/informazioni\/news\/come-registrare-un-video-con-la-webcam-del-mac-3-metodi-gratuiti#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.comparasemplice.it\/informazioni"},{"@type":"ListItem","position":2,"name":"Come registrare un video con la Webcam del Mac: 3 metodi gratuiti"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/44203"}],"collection":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/comments?post=44203"}],"version-history":[{"count":24,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/44203\/revisions"}],"predecessor-version":[{"id":63578,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/44203\/revisions\/63578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/media\/44224"}],"wp:attachment":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/media?parent=44203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/categories?post=44203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/tags?post=44203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}