{"id":8763,"date":"2021-06-04T17:47:10","date_gmt":"2021-06-04T15:47:10","guid":{"rendered":"https:\/\/www.comparasemplice.it\/informazioni\/internet-adsl-fibra-wimax\/disdetta-fastweb\/"},"modified":"2024-10-03T13:19:11","modified_gmt":"2024-10-03T11:19:11","slug":"disdetta-fastweb","status":"publish","type":"post","link":"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/disdetta-fastweb","title":{"rendered":"Disdetta Fastweb: la guida"},"content":{"rendered":"<p>Fastweb \u00e8 una delle poche <a href=\"https:\/\/www.comparasemplice.it\/adsl\/compagnie\">compagnie internet<\/a> a non avere particolari vincoli per quanto riguarda la durata minima del contratto ADSL o fibra: l\u2019attivazione del servizio, grazie alle continue <a href=\"https:\/\/www.comparasemplice.it\/internet-casa\">offerte internet casa<\/a> che si susseguono di mese in mese, \u00e8 sempre gratuita e il modem viene fornito in comodato d\u2019uso, senza costi per il cliente. L\u2019unico contributo che sar\u00e0 necessario pagare in caso di disdetta Fastweb \u00e8 quello relativo alla disattivazione.<\/p>\n<p>Se siete arrivati fin qui, tuttavia<strong>, \u00e8 probabile che vogliate chiudere un contratto Fastweb casa<\/strong>\u00a0perch\u00e9 non siete pi\u00f9 soddisfatti o perch\u00e9 avete bisogno di dismettere la linea (ad esempio a causa di un trasferimento o per il decesso dell&#8217;intestatario), ma non sapete come fare per procedere nella richiest. Nei prossimi paragrafi vedremo esattamente che cosa fare, quali sono i documenti da presentare, i costi da sostenere, ma anche le alternative da prendere in considerazione se non volete perdere definitivamente la linea.<\/p>\n<p><strong>Ricordiamo che la disdetta del contratto Fastweb deve essere presentata solo nel caso in cui si decida di chiudere definitivamente la linea<\/strong>, con la conseguente perdita del numero. Se, invece, state pensando di cambiare operatore (ad esempio per attivare una promozione migliore dopo aver fatto un confronto delle offerte Internet casa pi\u00f9 interessanti del periodo), sar\u00e0 il nuovo gestore ad occuparsi di tutte le pratiche necessarie per la chiusura del nuovo contratto (come vedremo in seguito nel paragrafo dedicato).<\/p>\n<p>La procedura di disdetta Fastweb da seguire <strong>\u00e8 valida sia per chi ha un contratto ADSL, sia per chi ha sottoscritto un\u2019<a href=\"https:\/\/www.comparasemplice.it\/fibra-ottica\">offerta fibra<\/a> (FTTC o FTTH) dell\u2019operatore<\/strong>. Anche il recesso della componente Mobile Fastweb \u00e8 molto simile, come potrete leggere verso la fine della guida.<\/p>\n<p>Sommario<\/p><div class=\"sommario\" id=\"indice\"><ol><li><a class=\"link_sommario\" href=\"#documenti-necessari-per-la-disdetta-fastweb\">Documenti necessari per la disdetta Fastweb<\/a><\/li><li><a class=\"link_sommario\" href=\"#come-fare-una-disdetta-fastweb\">Come fare una disdetta Fastweb<\/a><\/li><li><a class=\"link_sommario\" href=\"#disdetta-fastweb-costo-previsto\">Disdetta Fastweb: costo previsto<\/a><\/li><li><a class=\"link_sommario\" href=\"#come-restituire-il-modem-fastweb\">Come restituire il modem Fastweb<\/a><\/li><li><a class=\"link_sommario\" href=\"#tempistiche-disdetta-fastweb\">Tempistiche disdetta Fastweb<\/a><\/li><li><a class=\"link_sommario\" href=\"#disdetta-fastweb-entro-14-giorni-diritto-di-ripensamento\">Disdetta Fastweb entro 14 giorni (diritto di ripensamento)<\/a><\/li><li><a class=\"link_sommario\" href=\"#cambio-operatore-bisogna-fare-la-disdetta-fastweb\">Cambio operatore: bisogna fare la disdetta Fastweb?<\/a><\/li><li><a class=\"link_sommario\" href=\"#chiusura-abbonamento-sky-fastweb\">Chiusura abbonamento Sky &amp; Fastweb<\/a><\/li><li><a class=\"link_sommario\" href=\"#disdetta-fastweb-per-decesso\">Disdetta Fastweb per decesso<\/a><\/li><li><a class=\"link_sommario\" href=\"#subentro-fastweb\">Subentro Fastweb<\/a><\/li><li><a class=\"link_sommario\" href=\"#trasloco-fastweb-come-fare\">Trasloco Fastweb: come fare<\/a><\/li><li><a class=\"link_sommario\" href=\"#disdetta-fastweb-mobile-cosa-fare\">Disdetta Fastweb Mobile: cosa fare<\/a><\/li><li><a class=\"link_sommario\" href=\"#reclamo-fastweb\">Reclamo Fastweb<\/a><\/li><\/ol><\/div>\n<h2>Documenti necessari per la disdetta Fastweb<\/h2>\n<p>Per presentare correttamente una disdetta Fastweb \u00e8 necessario <strong>munirsi dei seguenti documenti<\/strong>:<\/p>\n<ul>\n<li>la fotocopia di un documento di identit\u00e0 in corso di validit\u00e0;<\/li>\n<li>il codice cliente Fastweb;<\/li>\n<li>un <strong><a href=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/05\/modulo-disdetta-fastweb.pdf\">modulo disdetta Fastweb<\/a>\u00a0<\/strong>per la linea fissa.<\/li>\n<\/ul>\n<p><strong>CONSIGLIO<\/strong>: se non conoscete o non ricordate il codice cliente, potrete scaricare una qualsiasi bolletta dall&#8217;area MyFastweb o dall&#8217;app. All&#8217;interno della fattura sono presenti tutti i dati importanti relativi alla linea, tra cui anche il codice identificativo del vostro contratto.<\/p>\n<h2>Come fare una disdetta Fastweb<\/h2>\n<p>Per effettuare una disdetta Fastweb <strong>baster\u00e0 inviare il modulo disdetta compilato, con in allegato la fotocopia del documento di identit\u00e0 dell\u2019intestatario del contratto<\/strong>, attraverso uno dei seguenti canali messi a disposizione dal provider:<\/p>\n<ul>\n<li>via PEC all\u2019indirizzo <strong>fwgestionedisattivazioni@pec.fastweb.it<\/strong>;<\/li>\n<li>inviando una raccomandata A\/R all\u2019indirizzo <strong>Fastweb S.p.A. Casella Postale 126, 20092 Cinisello Balsamo (MI)<\/strong>;<\/li>\n<li>inviando un <strong>messaggio<\/strong> <strong>WhatsApp<\/strong>\u00a0all&#8217;assistenza clienti Fastweb al numero <strong>3756497700<\/strong>,<\/li>\n<\/ul>\n<p>In alternativa \u00e8 possibile presentare richiesta di cessazione del servizio:<\/p>\n<ul>\n<li>attraverso il modulo online dedicato sull\u2019<strong>area MyFastweb<\/strong>, seguendo il percorso guidato dell&#8217;<a href=\"https:\/\/www.fastweb.it\/myfastweb\/assistenza\/\"><strong>area Supporto<\/strong><\/a>;<\/li>\n<li><strong>recandosi presso un negozio Fastweb<\/strong>;<\/li>\n<li>chiamando l\u2019assistenza Fastweb al numero <strong>192 193<\/strong>, gratuito da rete Fastweb (fissa o mobile);<\/li>\n<li>contattando dall&#8217;estero il numero +<b>393730004193<\/b>, attivo tutti i giorni dalle ore 8 alle 24 (e gratuito dai cellulari Fastweb).<\/li>\n<\/ul>\n<p>Anche in questi casi \u00e8<strong> consigliabile avere con s\u00e9 la copia del documento di identit\u00e0 e una fattura del gestore<\/strong>.<\/p>\n<h2>Disdetta Fastweb: costo previsto<\/h2>\n<p>Il costo della disdetta Fastweb in caso di cessazione del servizio o migrazione<strong> \u00e8 sempre pari a 29,95 euro una tantum<\/strong>. \u00c8 prevista la restituzione del modem in comodato d\u2019uso gratuito.<\/p>\n<p>Fastweb fa sapere che \u201c<em>in caso di mancata o ritardata restituzione degli apparati, quindi superati i 45 giorni dalla disattivazione del servizio Fastweb, <strong>ti verr\u00e0 addebitata la relativa penale pari a 50 \u20ac per il modem FASTGate<\/strong> . Invece <strong>per il Fastweb NeXXT \u00e8 prevista una penale pari a 80\u20ac e per il Wi-Fi Booster \u00e8 prevista una penale di 60\u20ac<\/strong>. Gli importi indicati sono IVA inclusa<\/em>\u201d.<\/p>\n<h2>Come restituire il modem Fastweb<\/h2>\n<p>Il modem ed eventuali altri apparati forniti in comodati d\u2019uso <strong>devono essere riconsegnati perfettamente integri entro 45 giorni<\/strong> dalla data di disattivazione del servizio. Il provider fornir\u00e0 i dettagli sulle modalit\u00e0 di restituzione con una comunicazione via mail e sms. Solo a seguito della ricezione della comunicazione <strong>sar\u00e0 possibile restituire gratis gli apparati attraverso Poste Italiane<\/strong>.<\/p>\n<p>Disdetta Fastweb gratis: quando \u00e8 possibile?<\/p>\n<p>\u00c8 possibile non pagare il costo di disattivazione sulla disdetta Fastweb soltanto nei seguenti casi:<\/p>\n<ul>\n<li><strong>in caso di ripensamento entro 14 giorni<\/strong>;<\/li>\n<li><strong>disdetta Fastweb richiesta a seguito di una modifica unilaterale del contratto<\/strong> da parte del provider;<\/li>\n<li><strong>disdetta Fastweb richiesta per mancato rispetto del contratto da parte del provider<\/strong> (ad esempio se si dimostrano disservizi prolungati nel tempo, se vengono applicati costi differenti rispetto a quelli previsti dall\u2019offerta o se non viene rispettata la <a href=\"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/velocita-minima-garantita-fastweb\"><strong>velocit\u00e0 Internet minima garantita da Fastweb<\/strong><\/a> di contratto).<\/li>\n<\/ul>\n<h2>Tempistiche disdetta Fastweb<\/h2>\n<p>La disattivazione della linea<strong> deve avvenire entro e non oltre 30 giorni dall\u2019accoglimento della richiesta di disdetta Fastweb<\/strong>. \u00c8 consigliabile, quindi, inviare la domanda con un certo preavviso, a seconda dell\u2019urgenza o meno della chiusura del contratto.<\/p>\n<h2>Disdetta Fastweb entro 14 giorni (diritto di ripensamento)<\/h2>\n<p>Grazie al diritto di recesso previsto dall\u2019<strong>art. 52 del Codice di Consumo<\/strong>, chi ha sottoscritto un abbonamento Fastweb online o telefonico <strong>da meno di 14 giorni pu\u00f2 recedere dal contratto con una semplice telefonata al Servizio Clienti Fastweb<\/strong>. \u00c8 la facolt\u00e0 che viene messa a disposizione dei consumatori che firmano un contratto a distanza, per evitare di dover intraprendere una procedura troppo lunga dopo sole poche settimane di abbonamento.<\/p>\n<p>Come abbiamo accennato in precedenza, in questo caso <strong>non \u00e8 previsto un contributo di disattivazione del servizio\u00a0<\/strong>come per una disattivazione o in caso di passaggio ad altro operatore mantenendo lo stesso numero,\u00a0ma potrebbe essere corrisposto \u201c<em>un importo proporzionale ai servizi forniti al momento in cui Fastweb \u00e8 venuta a conoscenza della tua richiesta di recesso<\/em>\u201d, come specifica il provider sul sito ufficiale. L&#8217;ammontare dell&#8217;importo, qualora venisse applicato, verr\u00e0 specificato al cliente dalla compagnia previa comunicazione.<\/p>\n<p>Per presentare la richiesta di recesso entro i primi 14 giorni<strong> bisogner\u00e0 compilare un modulo dedicato\u00a0<\/strong>(scaricabile a fine paragrafo in formato pdf)\u00a0e inviarlo, insieme ad una<strong> fotocopia di un documento di identit\u00e0\u00a0<\/strong>in corso di validit\u00e0, attraverso uno dei seguenti canali:<\/p>\n<ul>\n<li>via PEC a <strong>fwgestionedisattivazioni@pec.fastweb.it<\/strong>;<\/li>\n<li>via posta, con raccomandata A\/R, all\u2019indirizzo <strong>Fastweb Spa, c\/o C.P. n. 126, 20092 Cinisello Balsamo (MI)<\/strong>;<\/li>\n<li>consegnandolo di persona <strong>presso un negozio Fastweb<\/strong>.<\/li>\n<\/ul>\n<p>In alternativa \u00e8 possibile <strong>compilare il form online<\/strong> accedendo nella propria <strong>Area MyFastweb<\/strong> oppure chiamare telefonicamente il customer care dell&#8217;operatore al numero <strong>192 193<\/strong>.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/05\/modulo-ripensamento-fastweb-linea-fissa.pdf\"><strong>SCARICA IL MODULO DISDETTA FASTWEB ENTRO 14 GIORNI<\/strong><\/a><\/p>\n<h2>Cambio operatore: bisogna fare la disdetta Fastweb?<\/h2>\n<p>Avete trovato un\u2019offerta pi\u00f9 conveniente o Fastweb non soddisfa le aspettative di servizio? Una soluzione potrebbe essere il <strong>cambio dell\u2019operatore o migrazione<\/strong>, una procedura che richiede la sottoscrizione di un nuovo contratto con un altro provider. <strong>Quest\u2019ultimo si occuper\u00e0 della procedura di disdetta del vecchio rapporto in essere con Fastweb<\/strong> e, quindi, <strong>non \u00e8 necessario inviare una richiesta di chiusura del contratto<\/strong>.<\/p>\n<p>Per sottoscrivere un nuovo contratto \u00e8 necessario avere a portata di mano il <a href=\"https:\/\/www.comparasemplice.it\/adsl\/codice-migrazione\"><strong>codice di migrazione Fastweb<\/strong><\/a>, <strong>i documenti dell\u2019intestatario dell\u2019utenza (ad esempio la carta di identit\u00e0 e il codice fiscale) e i dati sul metodo di pagamento scelto<\/strong>.<\/p>\n<p>In caso di migrazione verso altro operatore, <strong>Fastweb richiede un contributo di disattivazione pari a 29,95 euro una tantum<\/strong>.<\/p>\n<p>\u00c8 necessario, inoltre, <strong>restituire il modem fornito in comodato d\u2019uso entro 45 giorni dalla disattivazione dei servizi da parte di Fastweb<\/strong>. La restituzione degli apparati in comodato d\u2019uso deve avvenire a seguito di una comunicazione da parte del provider circa le modalit\u00e0 di spedizione tramite Poste Italiane. Con alcune comunicazioni e-mail e SMS, Fastweb fornir\u00e0 al cliente anche il link alla lettera di vettura da consegnare a Poste, come gi\u00e0 visto in precedenza per la cessazione della linea.<\/p>\n<h2>Chiusura abbonamento Sky &amp; Fastweb<\/h2>\n<p>Se avete sottoscritto un abbonamento Sky &amp; Fastweb (non pi\u00f9 sottoscrivibile), la disdetta dell\u2019offerta congiunta deve essere inoltrata inviando esplicita richiesta, con in allegato un documento di identit\u00e0, in uno dei seguenti canali.<\/p>\n<ul>\n<li>via <strong>PEC a skyitalia@pec.skytv.it<\/strong>;<\/li>\n<li>via posta all\u2019indirizzo <strong>Sky Italia S.r.l., c\/o Casella Postale 13057, 20130 Milano<\/strong>.<\/li>\n<\/ul>\n<p>In alternativa si pu\u00f2 seguire la<a href=\"https:\/\/assistenza.sky.it\/abbonamento\/guida-info-disdetta-sky#moduli\"><strong> pagina di disdetta o recesso dell&#8217;abbonamento Sky<\/strong><\/a>\u00a0sul sito ufficiale dell&#8217;azienda.<\/p>\n<h2>Disdetta Fastweb per decesso<\/h2>\n<p><a href=\"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/disdetta-fastweb-per-decesso-ecco-come-fare\"><strong>Vai alla guida dedicata alla disdetta Fastweb per decesso &gt;<\/strong><\/a><\/p>\n<p>Per presentare una richiesta di chiusura del contratto a causa del decesso dell&#8217;intestatario \u00e8 consigliabile<strong> compilare il <a href=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/05\/modulo-disdetta-fastweb.pdf\">modulo disdetta Fastweb<\/a><\/strong>, indicando sulla voce \u201c<strong>Altro<\/strong>\u201d la motivazione della richiesta di chiusura (\u201c<strong>decesso dell\u2019intestatario<\/strong>\u201d appunto). Il modulo, con <strong>in allegato le fotocopie di un documento di identit\u00e0 e del certificato di morte dell&#8217;intestatario<\/strong>, deve essere inviato attraverso uno dei seguenti canali:<\/p>\n<ul>\n<li>via PEC a fwgestionedisattivazioni@pec.fastweb.it;<\/li>\n<li>via posta, con raccomandata A\/R, all\u2019indirizzo Fastweb Spa, c\/o C.P. n. 126, 20092 Cinisello Balsamo (MI).<\/li>\n<\/ul>\n<p>In alternativa<strong> \u00e8 possibile presentare la documentazione presso un negozio Fastweb<\/strong>. Per dubbi o per maggiori informazioni \u00e8 consigliabile contattare l\u2019assistenza clienti del provider al numero 192 193.<\/p>\n<p>La disdetta Fastweb per decesso <strong>segue praticamente la stessa procedura di una normale disdetta<\/strong>: i tempi di attesa saranno anch&#8217;essi di <strong>circa 30 giorni<\/strong>, a volte anche meno. Gli eventuali addebiti pervenuti dopo l\u2019accoglimento della domanda vengono rimborsati dal provider. <strong>Non sono previsti costi di disattivazione o penali ma \u00e8 necessario restituire il modem Fastweb in comodato d\u2019uso ed eventuali altri apparati inclusi<\/strong>\u00a0nell\u2019offerta che \u00e8 stata sottoscritta dall\u2019utente che \u00e8 venuto a mancare.<\/p>\n<h2>Subentro Fastweb<\/h2>\n<p>Se non volete perdere la linea telefonica e il vecchio intestatario non \u00e8 pi\u00f9 presente (ad esempio se ci si trasferisce presso una nuova abitazione con abbonamento Fastweb attivo o se il precedente intestatario \u00e8 deceduto), potete <strong>richiedere un cambio dell\u2019intestatario<\/strong>, il cosiddetto <strong>subentro<\/strong>,\u00a0anzich\u00e9 fare una disdetta telefonica: in questo modo <strong>il contratto sar\u00e0 a nome di un\u2019altra persona e il servizio non subir\u00e0 alcuna interruzione<\/strong>. In ogni caso il subentro <strong>\u00e8 possibile solo se le vecchie bollette sono state pagate tutte e se non vi sono delle modifiche pendenti sul contratto<\/strong>.<\/p>\n<p>Per poter presentare la domanda di subentro Fastweb dovrete <strong>compilare il modulo dedicato che trovate in formato PDF qui in basso<\/strong> e inoltrarlo attraverso uno dei seguenti canali:<\/p>\n<ul>\n<li>via mail a <strong>documentionline@fastweb.it<\/strong>;<\/li>\n<li>via fax al numero <strong>02 454011077<\/strong>.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/05\/modulo-subentro-fastweb.pdf\" target=\"_blank\" rel=\"noopener\">SCARICA IL MODULO SUBENTRO FASTWEB<\/a><\/strong><\/p>\n<p><strong>Il costo per un subentro Fastweb \u00e8 pari a 20,34 euro<\/strong>, IVA inclusa (che verr\u00e0 addebitato sulla prima fattura a nome del nuovo utente), anche in caso di cambio per decesso dell\u2019intestatario precedente, mentre le tempistiche si aggirano attorno ai 30 giorni.\u00a0\u00c8 possibile\u00a0comunque contattare il customer care della compagnia per avere maggiori informazioni in merito al cambio intestatario e alle modalit\u00e0 di subentro in base al contratto sottoscritto in precedenza.<\/p>\n<h2>Trasloco Fastweb: come fare<\/h2>\n<p>Per effettuare un trasloco della linea Fastweb non \u00e8 necessario dover presentare una disdetta. Per presentare la richiesta \u00e8 necessario seguire i seguenti passaggi:<\/p>\n<ul>\n<li>verificare la disponibilit\u00e0 del servizio Fastweb al nuovo indirizzo da<a href=\"https:\/\/www.fastweb.it\/myfastweb\/assistenza\/assistente-online\/trasloco\/\"><strong> questa pagina<\/strong><\/a>;<\/li>\n<li>compilare il modulo di richiesta;<\/li>\n<li>attendere la chiamata dell\u2019assistenza commerciale Fastweb per concludere la richiesta.<\/li>\n<\/ul>\n<p>La procedura <strong>pu\u00f2 essere effettuata sia da computer, sia da smartphone o tablet, scaricando l\u2019app gratuita MyFastweb<\/strong>.<\/p>\n<p><strong>Il costo di un trasloco \u00e8 pari a 35,58 euro, IVA inclusa<\/strong>, mentre <strong>i tempi di trasferimenti variano da un minimo di 25 giorni ad un massimo di 50 giorni,<\/strong> a seconda della copertura tecnologica. Per questo motivo <strong>\u00e8 consigliabile inviare la richiesta con un preavviso di almeno 50 giorni dalla data effettiva del trasloco<\/strong>.<\/p>\n<h2>Disdetta Fastweb Mobile: cosa fare<\/h2>\n<p>Per la disdetta di un contratto con <a href=\"https:\/\/www.comparasemplice.it\/offerte-sim-cellulare\/operatori\/fastweb-mobile\">Fastweb Mobile<\/a>, non \u00e8 necessario presentare una richiesta specifica: <strong>\u00e8 sufficiente non ricaricare la scheda per 12 mesi consecutivi per farla scadere definitivamente<\/strong>. Ovviamente<strong> il numero associato alla sim verr\u00e0 definitivamente perso<\/strong>. In alternativa \u00e8 possibile fare esplicita richiesta compilando un <a href=\"https:\/\/cdn3.comparasemplice.it\/informazioni\/wp-content\/uploads\/2021\/05\/modulo-disdetta-fastweb-mobile.pdf\"><strong>modulo di disdetta Fastweb Mobile<\/strong><\/a> e inoltrandolo <strong>insieme alla fotocopia di un documento di identit\u00e0<\/strong> attraverso uno dei seguenti canali:<\/p>\n<ul>\n<li>via PEC a <strong>fwgestionedisattivazioni@pec.fastweb.it<\/strong>;<\/li>\n<li>via posta, con raccomandata A\/R, all\u2019indirizzo <strong>Fastweb Spa, c\/o C.P. n. 126, 20092 Cinisello Balsamo (MI)<\/strong>;<\/li>\n<li>recandosi <strong>presso un negozio Fastweb<\/strong>.<\/li>\n<\/ul>\n<p>In alternativa potete contattare l\u2019assistenza clienti Fastweb al numero <strong>192 193\u00a0<\/strong>e richiedere la disattivazione.\u00a0 Per maggiori informazioni vi rimandiamo alla nostra <a href=\"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/come-disattivare-sim-fastweb\"><strong>guida su come disattivare una sim Fastweb<\/strong><\/a>.<\/p>\n<p>Un\u2019altra opzione \u00e8 quella della <strong>portabilit\u00e0 verso un altro operatore, approfittando delle numerose promozioni previste per i nuovi clienti<\/strong>: in questo caso, per\u00f2, <strong>non \u00e8 necessario presentare disdetta<\/strong>, come nel caso di migrazione di una linea fissa.<\/p>\n<h2>Reclamo Fastweb<\/h2>\n<p>Se volete contestare degli <strong>addebiti non dovuti dall\u2019operatore a seguito della disattivazione<\/strong> o <strong>se continuano ad arrivarvi bollette nonostante la richiesta di recesso Fastweb<\/strong>, potete presentare un reclamo alla compagnia in modo da risolvere in tempi brevi questi spiacevoli problemi.<\/p>\n<p>Per presentare un reclamo, Fastweb consiglia di utilizzare i seguenti canali:<\/p>\n<p>la sezione assistenza \u201c<a href=\"https:\/\/www.fastweb.it\/myfastweb\/assistenza\/\"><strong>Supporto Fastweb<\/strong><\/a>\u201d, seguendo la procedura guidata in base alla problematica;<\/p>\n<p>inviando una raccomandata A\/R all\u2019indirizzo <strong>Fastweb Spa, c\/o C.P. n. 126, 20092 Cinisello Balsamo (MI)<\/strong>.<\/p>\n<p>\u00c8 possibile <strong>inviare un ulteriore reclamo entro 30 giorni dal completamento della gestione<\/strong> del primo direttamente dalla <strong>sezione Le mie richieste dell\u2019area MyFastweb<\/strong>.<\/p>\n<p>Il provider, inoltre, fa sapere che \u201c<em>se al termine della gestione del reclamo ritieni che i tuoi diritti non siano stati tutelati, ti ricordiamo che <strong>puoi sempre ricorrere alla Procedura di Conciliazione con una delle Associazioni che hanno sottoscritto con Fastweb il protocollo di conciliazione<\/strong><\/em>\u201d. Sar\u00e0 quindi possibile inoltrare la richiesta<\/p>\n<ul>\n<li>alle Associazioni dei Consumatori<\/li>\n<li>autonomamente, seguendo le indicazioni presenti sulla <a href=\"https:\/\/www.fastweb.it\/corporate\/governance\/conciliazioni-e-associazioni-consumatori\/\"><strong>pagina Fastweb dedicata alle Conciliazioni<\/strong><\/a>.<\/li>\n<\/ul>\n<p>Abbiamo visto, quindi, come fare una disdetta Fastweb correttamente, sia su fisso (<a href=\"https:\/\/www.comparasemplice.it\/adsl\">offerte ADSL<\/a> o fibra) che su mobile, quali sono i tempi e i costi da sostenere. Non solo: abbiamo anche approfondito le alternative, come il subentro e il trasloco di una linea Fastweb, molto utili se non volete perdere il numero associato al contratto, e come presentare un reclamo in caso di addebiti indesiderati o altri problemi.<\/p>\n<p>Non siete ancora sicuri se effettuare una disdetta o se passare ad un altro provider? Scrivete subito una mail a <strong>info@comparasemplice.it<\/strong> o <strong>aprite una live chat<\/strong>\u00a0direttamente sul sito per avere la<strong> consulenza gratuita e senza impegno di un esperto<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fastweb \u00e8 una delle poche compagnie internet a non avere particolari vincoli per quanto riguarda la durata minima del contratto&#8230;<\/p>\n","protected":false},"author":49,"featured_media":40671,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43,35],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disdetta Fastweb<\/title>\n<meta name=\"description\" content=\"Come effettuare la disdetta Fastweb: iter, canali e moduli per disdire un abbonamento con Fastweb. La guida di ComparaSemplice.it.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/disdetta-fastweb\" \/>\n<meta name=\"author\" content=\"Silvio Spina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/disdetta-fastweb#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.comparasemplice.it\/informazioni\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Disdetta Fastweb: la guida\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disdetta Fastweb","description":"Come effettuare la disdetta Fastweb: iter, canali e moduli per disdire un abbonamento con Fastweb. La guida di ComparaSemplice.it.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/disdetta-fastweb","author":"Silvio Spina","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comparasemplice.it\/informazioni\/fastweb\/disdetta-fastweb#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.comparasemplice.it\/informazioni"},{"@type":"ListItem","position":2,"name":"Disdetta Fastweb: la guida"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/8763"}],"collection":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/comments?post=8763"}],"version-history":[{"count":16,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/8763\/revisions"}],"predecessor-version":[{"id":61302,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/posts\/8763\/revisions\/61302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/media\/40671"}],"wp:attachment":[{"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/media?parent=8763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/categories?post=8763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparasemplice.it\/informazioni\/wp-json\/wp\/v2\/tags?post=8763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}